{"id":7786,"count":1,"description":"","link":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/","name":"Lolita","slug":"lolita","taxonomy":"post_tag","meta":[],"yoast_head":"\n<title>Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/\" \/>\n<meta property=\"og:site_name\" content=\"Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@jason_debord\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/tag\\\/lolita\\\/\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/tag\\\/lolita\\\/\",\"name\":\"Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/tag\\\/lolita\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/tag\\\/lolita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lolita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\",\"name\":\"Movie Prop Collecting with Jason DeBord's Original Prop Blog Film & TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#organization\",\"name\":\"Original Prop Blog\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Original-Prop-Blog-Vimeo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Original-Prop-Blog-Vimeo.jpg\",\"width\":300,\"height\":300,\"caption\":\"Original Prop Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/originalpropblog\",\"https:\\\/\\\/x.com\\\/jason_debord\"]}]}<\/script>\n","yoast_head_json":{"title":"Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/","og_locale":"en_US","og_type":"article","og_title":"Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","og_url":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/","og_site_name":"Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","twitter_card":"summary_large_image","twitter_site":"@jason_debord","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/","url":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/","name":"Lolita Archives - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","isPartOf":{"@id":"https:\/\/www.originalprop.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.originalprop.com\/blog\/tag\/lolita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.originalprop.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Lolita"}]},{"@type":"WebSite","@id":"https:\/\/www.originalprop.com\/blog\/#website","url":"https:\/\/www.originalprop.com\/blog\/","name":"Movie Prop Collecting with Jason DeBord's Original Prop Blog Film & TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","description":"","publisher":{"@id":"https:\/\/www.originalprop.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.originalprop.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.originalprop.com\/blog\/#organization","name":"Original Prop Blog","url":"https:\/\/www.originalprop.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2025\/05\/Original-Prop-Blog-Vimeo.jpg","contentUrl":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2025\/05\/Original-Prop-Blog-Vimeo.jpg","width":300,"height":300,"caption":"Original Prop Blog"},"image":{"@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/originalpropblog","https:\/\/x.com\/jason_debord"]}]}},"_links":{"self":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/tags\/7786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/posts?tags=7786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}