{"id":19546,"date":"2010-04-05T20:20:40","date_gmt":"2010-04-06T04:20:40","guid":{"rendered":"http:\/\/www.originalprop.com\/blog\/?p=19546"},"modified":"2026-05-01T20:39:55","modified_gmt":"2026-05-02T03:39:55","slug":"original-prop-blog-three-year-anniversary","status":"publish","type":"post","link":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/","title":{"rendered":"Original Prop Blog: Three Year Anniversary"},"content":{"rendered":"<p><a href=\"http:\/\/www.originalprop.com\/blog\/?p=11642\" target=\"_self\"><\/a><a href=\"http:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19548\" title=\"Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380\" src=\"http:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\" alt=\"Original Prop Blog: Three Year Anniversary | Jason DeBord Original Prop Blog Movie Magazine 3 Year Anniversary x380\" width=\"380\" height=\"92\" srcset=\"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg 380w, https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380-300x72.jpg 300w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><\/p>\n<p>Today marks the three year anniversary of the Original Prop Blog.\u00a0 Three years ago today I published its first article, &#8220;<a href=\"http:\/\/www.originalprop.com\/blog\/?p=11\" target=\"_blank\">The  Hobby Without A Name&#8230;<\/a>&#8220;<img decoding=\"async\" title=\"More...\" src=\"http:\/\/www.originalprop.com\/blog\/ipsoxefa\/js\/tinymce\/plugins\/wordpress\/img\/trans.gif\" alt=\"Original Prop Blog: Three Year Anniversary | trans\" \/><\/p>\n<p>1,154 articles later, the website continues to grow, and I hope  that collectors around the world find it to be a useful resource.\u00a0 With  the <a href=\"http:\/\/www.originalprop.com\/blog\/2010\/04\/01\/original-prop-blog-monthly-web-site-traffic-statistics-march-2010\/\" target=\"_blank\">statistics  reported for the end of last month<\/a>, to date the site has received  over 5 million page views and over 50 million hits, averaging about 80,000 unique visitors per month.<\/p>\n<p>Of course, publishing articles on the Original Prop Blog has been an incredible learning experience for me, and I&#8217;ve been in the unique position of being able to see first hand both the best and the worst the hobby has to offer.<\/p>\n<p>I would say that the one thing that stands out to me the most is that the hobby at large does seem to be much more educated and discerning in navigating the marketplace compared with years ago.\u00a0 I think in part due to better communication across a number of discussion forums and other networking tools and perhaps in part due to a decrease in the number of new collectors coming into the hobby (both observations of which are entirely subjective and speculative on my part).<\/p>\n<p>Having said that, there is no shortage of large quantities of fake and inconclusive pieces being introduced to and circulating within the marketplace, and rarely any consequence for trading in such goods.<\/p>\n<h3>Original Prop Blog Search<\/h3>\n<p>As a reminder, given that the OPB has a tremendous amount of content, it is helpful  to know the best way to find and access it.<\/p>\n<p>The easiest and most powerful way to find what you are looking for is  to use the &#8220;Search&#8221; button in the top right hand corner of every  screen:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"search-the-original-prop-blog\" src=\"http:\/\/www.originalprop.com\/blog\/dylsoagh\/2009\/04\/search-the-original-prop-blog.jpg\" alt=\"search-the-original-prop-blog\" width=\"300\" height=\"61\" \/><\/p>\n<h3>The Year Ahead<\/h3>\n<p>As always, there are many plans in the works to offer more compelling content over the coming year and to continue to build on the &#8220;Original Prop Blog&#8221; brand with new features.\u00a0 Hopefully, one of these new regular features will debut in the next month or so.<\/p>\n<p>Of course, the site is in many ways built upon the support, tips, and participation of fellow hobbyists and readers of the blog, so special thanks again to all of those who give the OPB purpose.<\/p>\n<p>Jason De Bord<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Today marks the three year anniversary of the Original Prop Blog.\u00a0 Three years ago today I published its first article, &#8220;The Hobby Without A Name&#8230;&#8220;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[5,2000],"tags":[338,599,604,171,598,31,463,399,211,273,1335,21,210,594,608,22,600,97,398,3300,588,3631,3632,3634,60,19,51,54,243,18,1166,3294,3259,3635,3297,3299,3298,209,478,20,605,3301,585,591,596,23,2035,167,24],"class_list":{"0":"post-19546","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-editorials-features","7":"category-featured-articles","8":"tag-archive","9":"tag-archiving","10":"tag-archivist","11":"tag-authentic","12":"tag-authenticate","13":"tag-blog","14":"tag-collect","15":"tag-collecting","16":"tag-collection","17":"tag-collector","18":"tag-collectors","19":"tag-costume","20":"tag-culture","21":"tag-debate","22":"tag-discussion","23":"tag-film","24":"tag-forum","25":"tag-fraud","26":"tag-hobby","27":"tag-hobbyist","28":"tag-information","29":"tag-jason-de-bord","30":"tag-jason-debord","31":"tag-jdebord","32":"tag-memorabilia","33":"tag-movie","34":"tag-museum","35":"tag-news","36":"tag-online","37":"tag-original","38":"tag-original-prop-blog","39":"tag-original-prop-community","40":"tag-original-prop-directory","41":"tag-originalpropblog","42":"tag-originalpropblogcom","43":"tag-originalpropcommunitycom","44":"tag-originalpropdirectorycom","45":"tag-pop","46":"tag-private","47":"tag-prop","48":"tag-public","49":"tag-register","50":"tag-research","51":"tag-reviews","52":"tag-selling","53":"tag-television","54":"tag-transparency","55":"tag-tv","56":"tag-wardrobe","57":"entry"},"yoast_head":"\n<title>Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\" \/>\n<meta property=\"og:description\" content=\"Today marks the three year anniversary of the Original Prop Blog.\u00a0 Three years ago today I published its first article, &#8220;The Hobby Without A Name&#8230;&#8220;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/\" \/>\n<meta property=\"og:site_name\" content=\"Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/originalpropblog\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-06T04:20:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-02T03:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"380\" \/>\n\t<meta property=\"og:image:height\" content=\"92\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jason DeBord\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@jason_debord\" \/>\n<meta name=\"twitter:site\" content=\"@jason_debord\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jason DeBord\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/\"},\"author\":{\"name\":\"Jason DeBord\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/person\\\/bdb327ea93e27defacdf4c1618889aea\"},\"headline\":\"Original Prop Blog: Three Year Anniversary\",\"datePublished\":\"2010-04-06T04:20:40+00:00\",\"dateModified\":\"2026-05-02T03:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/\"},\"wordCount\":390,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\",\"keywords\":[\"archive\",\"archiving\",\"archivist\",\"authentic\",\"authenticate\",\"blog\",\"collect\",\"collecting\",\"Collection\",\"collector\",\"collectors\",\"Costume\",\"Culture\",\"debate\",\"discussion\",\"Film\",\"forum\",\"Fraud\",\"hobby\",\"hobbyist\",\"information\",\"Jason De Bord\",\"Jason DeBord\",\"jdebord\",\"memorabilia\",\"Movie\",\"Museum\",\"news\",\"online\",\"Original\",\"original prop blog\",\"Original Prop Community\",\"Original Prop Directory\",\"originalpropblog\",\"OriginalPropBlog.com\",\"OriginalPropCommunity.com\",\"OriginalPropDirectory.com\",\"Pop\",\"private\",\"Prop\",\"public\",\"register\",\"research\",\"reviews\",\"selling\",\"Television\",\"transparency\",\"tv\",\"Wardrobe\"],\"articleSection\":[\"Editorials\",\"Featured Articles\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/\",\"name\":\"Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\",\"datePublished\":\"2010-04-06T04:20:40+00:00\",\"dateModified\":\"2026-05-02T03:39:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\",\"contentUrl\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/04\\\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg\",\"width\":\"380\",\"height\":\"92\",\"caption\":\"Original Prop Blog: Three Year Anniversary | Jason DeBord Original Prop Blog Movie Magazine 3 Year Anniversary x380\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/2010\\\/04\\\/05\\\/original-prop-blog-three-year-anniversary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Original Prop Blog: Three Year Anniversary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\",\"name\":\"Movie Prop Collecting with Jason DeBord's Original Prop Blog Film & TV Prop, Costume, Hollywood Memorablia Pop Culture Resource\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#organization\",\"name\":\"Original Prop Blog\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Original-Prop-Blog-Vimeo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Original-Prop-Blog-Vimeo.jpg\",\"width\":300,\"height\":300,\"caption\":\"Original Prop Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/originalpropblog\",\"https:\\\/\\\/x.com\\\/jason_debord\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/#\\\/schema\\\/person\\\/bdb327ea93e27defacdf4c1618889aea\",\"name\":\"Jason DeBord\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg\",\"caption\":\"Jason DeBord\"},\"description\":\"Jason DeBord is a collector of original props and wardrobe\",\"sameAs\":[\"http:\\\/\\\/www.originalpropblog.com\"],\"url\":\"https:\\\/\\\/www.originalprop.com\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n","yoast_head_json":{"title":"Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/","og_locale":"en_US","og_type":"article","og_title":"Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","og_description":"Today marks the three year anniversary of the Original Prop Blog.\u00a0 Three years ago today I published its first article, &#8220;The Hobby Without A Name&#8230;&#8220;","og_url":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/","og_site_name":"Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","article_publisher":"https:\/\/www.facebook.com\/originalpropblog","article_published_time":"2010-04-06T04:20:40+00:00","article_modified_time":"2026-05-02T03:39:55+00:00","og_image":[{"width":380,"height":92,"url":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg","type":"image\/jpeg"}],"author":"Jason DeBord","twitter_card":"summary_large_image","twitter_creator":"@jason_debord","twitter_site":"@jason_debord","twitter_misc":{"Written by":"Jason DeBord","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#article","isPartOf":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/"},"author":{"name":"Jason DeBord","@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/person\/bdb327ea93e27defacdf4c1618889aea"},"headline":"Original Prop Blog: Three Year Anniversary","datePublished":"2010-04-06T04:20:40+00:00","dateModified":"2026-05-02T03:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/"},"wordCount":390,"commentCount":1,"publisher":{"@id":"https:\/\/www.originalprop.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#primaryimage"},"thumbnailUrl":"http:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg","keywords":["archive","archiving","archivist","authentic","authenticate","blog","collect","collecting","Collection","collector","collectors","Costume","Culture","debate","discussion","Film","forum","Fraud","hobby","hobbyist","information","Jason De Bord","Jason DeBord","jdebord","memorabilia","Movie","Museum","news","online","Original","original prop blog","Original Prop Community","Original Prop Directory","originalpropblog","OriginalPropBlog.com","OriginalPropCommunity.com","OriginalPropDirectory.com","Pop","private","Prop","public","register","research","reviews","selling","Television","transparency","tv","Wardrobe"],"articleSection":["Editorials","Featured Articles"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/","url":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/","name":"Original Prop Blog: Three Year Anniversary - Movie Prop Collecting with Jason DeBord&#039;s Original Prop Blog Film &amp; TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","isPartOf":{"@id":"https:\/\/www.originalprop.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#primaryimage"},"image":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#primaryimage"},"thumbnailUrl":"http:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg","datePublished":"2010-04-06T04:20:40+00:00","dateModified":"2026-05-02T03:39:55+00:00","breadcrumb":{"@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#primaryimage","url":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg","contentUrl":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2010\/04\/Jason-DeBord-Original-Prop-Blog-Movie-Magazine-3-Year-Anniversary-x380.jpg","width":"380","height":"92","caption":"Original Prop Blog: Three Year Anniversary | Jason DeBord Original Prop Blog Movie Magazine 3 Year Anniversary x380"},{"@type":"BreadcrumbList","@id":"https:\/\/www.originalprop.com\/blog\/2010\/04\/05\/original-prop-blog-three-year-anniversary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.originalprop.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Original Prop Blog: Three Year Anniversary"}]},{"@type":"WebSite","@id":"https:\/\/www.originalprop.com\/blog\/#website","url":"https:\/\/www.originalprop.com\/blog\/","name":"Movie Prop Collecting with Jason DeBord's Original Prop Blog Film & TV Prop, Costume, Hollywood Memorablia Pop Culture Resource","description":"","publisher":{"@id":"https:\/\/www.originalprop.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.originalprop.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.originalprop.com\/blog\/#organization","name":"Original Prop Blog","url":"https:\/\/www.originalprop.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2025\/05\/Original-Prop-Blog-Vimeo.jpg","contentUrl":"https:\/\/www.originalprop.com\/blog\/dylsoagh\/2025\/05\/Original-Prop-Blog-Vimeo.jpg","width":300,"height":300,"caption":"Original Prop Blog"},"image":{"@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/originalpropblog","https:\/\/x.com\/jason_debord"]},{"@type":"Person","@id":"https:\/\/www.originalprop.com\/blog\/#\/schema\/person\/bdb327ea93e27defacdf4c1618889aea","name":"Jason DeBord","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/518172167ed774f853f0b09d6cd3f3975ad0fe2d1321605be9a36aa827b88f4d?s=96&d=mm&r=pg","caption":"Jason DeBord"},"description":"Jason DeBord is a collector of original props and wardrobe","sameAs":["http:\/\/www.originalpropblog.com"],"url":"https:\/\/www.originalprop.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/posts\/19546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/comments?post=19546"}],"version-history":[{"count":4,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/posts\/19546\/revisions"}],"predecessor-version":[{"id":46963,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/posts\/19546\/revisions\/46963"}],"wp:attachment":[{"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/media?parent=19546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/categories?post=19546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.originalprop.com\/blog\/wp-json\/wp\/v2\/tags?post=19546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}